{"id":1743,"date":"2020-12-28T23:38:24","date_gmt":"2020-12-28T23:38:24","guid":{"rendered":"http:\/\/flangecoupling.top\/in-bhiwandi-india-sales-price-shop-near-me-near-me-shop-factory-supplier-heavy-duty-mining-processing-centrifugal-slurry-pump-ce-iso-sgs-approved-manufacturer-best-cost-cus\/"},"modified":"2022-11-07T02:41:11","modified_gmt":"2022-11-07T02:41:11","slug":"in-bhiwandi-india-sales-price-shop-near-me-near-me-shop-factory-supplier-heavy-duty-mining-processing-centrifugal-slurry-pump-ce-iso-sgs-approved-manufacturer-best-cost-cus","status":"publish","type":"post","link":"https:\/\/flangecoupling.top\/hi\/application\/in-bhiwandi-india-sales-price-shop-near-me-near-me-shop-factory-supplier-heavy-duty-mining-processing-centrifugal-slurry-pump-ce-iso-sgs-approved-manufacturer-best-cost-cus\/","title":{"rendered":"in Bhiwandi India  sales \r\n price \r\n shop \r\n near me \r\n near me shop \r\n factory \r\n supplier Heavy Duty Mining Processing Centrifugal Slurry Pump Ce ISO SGS Approved manufacturer \r\n best \r\n Cost \r\n Custom \r\n Cheap \r\n wholesaler"},"content":{"rendered":"<p><img decoding=\"async\" style=\"height:autowidth: auto\" title=\"  in Bhiwandi India  sales   price   shop   near me   near me shop   factory   supplier Heavy Duty Mining Processing Centrifugal Slurry Pump Ce ISO SGS Approved manufacturer   best   Cost   Custom   Cheap   wholesaler \" src=\"http:\/\/img.hzpt.com\/uploads\/images\/Jcj\/coupling.jpg\" alt=\"  in Bhiwandi India  sales   price   shop   near me   near me shop   factory   supplier Heavy Duty Mining Processing Centrifugal Slurry Pump Ce ISO SGS Approved manufacturer   best   Cost   Custom   Cheap   wholesaler \" \/><\/p>\n<p><p> In this way, our merchandise have continued to acquire industry acceptance and clients gratification above the previous couple of several years. Furthermore, WE CAN Make Tailored VARIATORS, GEARED MOTORS, Electric powered MOTORS AND OTHER HYDRAULIC Merchandise According TO CUSTOMERS\u2019 DRAWINGS. With a lot of years&#8217; expertise in this line, we will be trustworthy by our advantages in competitive cost, a single-time shipping, prompt response, on-hand engineering assistance and very good following-sales companies.In addition, all our production methods are in compliance with ISO9001 expectations.                                  <strong>EPT Duty EPT Processing Centrifugal EPT EPT CE\/ISO\/SGS Accepted<\/strong><\/p>\n<p><strong>Item Description<\/strong><br \/><strong>HS (R)Collection Introduction::<br \/>HS(R) pump is horizontal centrifugal heavy duty slurry pump and it is made for the steady pumping of large abrasive, EPT slurries with minimum servicing needs. It will preserve high effectiveness over the use life of its parts. The rubber and metal lined pumps feature casings which are radially spEPTT into two halves. Bare minimum casing bolts reduce upkeep and minimise downtime. The pumps of HS can be installed as multi-stage series.<\/strong><\/p>\n<p><strong>Features:<\/strong><br \/><strong>1.Replaceable dress in-resistant steel or rubber liners and impellers, EPTT provider lifestyle time.<br \/>two. EPT to alter the place amongst impeller and JCEP liner and can be eliminated totally when mainXiHu (West EPT) Dis.Hu (West EPT) Dis..<br \/>three.EPTT assembly use grease lubrication.<br \/>4. Seal varieties: EPTT seal, expeller seal and mechanical seal.<br \/>5. Discharge path can be put in at intervals of forty five degrees as ask for and oriEPTTd to any eigEPTT positions to suit apps.<br \/>6. JCEP kinds: V belt EPT, EPT EPTT EPT, fluid coupling EPT, and frequency conversion EPT units.<br \/>seven. Extensive application, great NPSH and large performance. The series pump can be installed in multistage to meet up with the shipping for EPTT distance.<\/strong><\/p>\n<p><strong>Specification :<\/strong><br \/><strong>D:25 mm to 450 mm<br \/>Q: to five,000 m3\/hr<br \/>H: to 73 m<\/strong><\/p>\n<p><strong>Performance Sheet:<\/strong> <\/p>\n<table>\n<tbody>\n<tr>\n<td rowspan=\"3\">\n<p><strong>EPT<br \/>Product<\/strong><\/td>\n<td rowspan=\"3\"><strong>Allowable<br \/>Max. EPTT(KW)<\/strong><\/td>\n<td colspan=\"6\"><strong>Very clear JCEP Overall performance<\/strong><\/td>\n<td><strong> <\/strong><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><strong>Capability Q<\/strong><\/td>\n<td rowspan=\"2\"><strong>EPT<br \/>H(m)<\/strong><\/td>\n<td rowspan=\"2\"><strong>Velocity<br \/>n(r\/min)<\/strong><\/td>\n<td rowspan=\"2\"><strong>Max.Eff.<br \/> eta%<\/strong><\/td>\n<td rowspan=\"2\"><strong>NPSH<br \/>(m)<\/strong><\/td>\n<td rowspan=\"2\"><strong>EPTTeller<br \/>Dia.<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>m3\/h<\/strong><\/td>\n<td><strong>l\/s<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>25HS-B<\/strong><\/td>\n<td><strong>fifteen<\/strong><\/td>\n<td><strong>12.6-28.8<\/strong><\/td>\n<td><strong>3.5-8<\/strong><\/td>\n<td><strong>six-sixty eight<\/strong><\/td>\n<td><strong>1200-3800<\/strong><\/td>\n<td><strong>forty<\/strong><\/td>\n<td><strong>2-4<\/strong><\/td>\n<td><strong>152<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>25HSR-B<\/strong><\/td>\n<td><strong>15<\/strong><\/td>\n<td><strong>ten.eight-twenty five.two<\/strong><\/td>\n<td><strong>three-7<\/strong><\/td>\n<td><strong>seven-52<\/strong><\/td>\n<td><strong>1400-3400<\/strong><\/td>\n<td><strong>35<\/strong><\/td>\n<td><strong> <\/strong><\/td>\n<td><strong> <\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>25HHS-C<\/strong><\/td>\n<td><strong>thirty<\/strong><\/td>\n<td><strong>sixteen.two-34.2<\/strong><\/td>\n<td><strong>four.5-nine.5<\/strong><\/td>\n<td><strong>25-ninety two<\/strong><\/td>\n<td><strong>1400-2200<\/strong><\/td>\n<td><strong>20<\/strong><\/td>\n<td><strong>two-5.5<\/strong><\/td>\n<td><strong>330<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>40HS-B<\/strong><\/td>\n<td><strong>15<\/strong><\/td>\n<td><strong>32.4-seventy two<\/strong><\/td>\n<td><strong>nine-20<\/strong><\/td>\n<td><strong>6-fifty eight<\/strong><\/td>\n<td><strong>1200-3200<\/strong><\/td>\n<td><strong>45<\/strong><\/td>\n<td><strong>3.five-eight<\/strong><\/td>\n<td><strong>184<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>40HSR-B<\/strong><\/td>\n<td><strong>fifteen<\/strong><\/td>\n<td><strong>25.two-fifty four<\/strong><\/td>\n<td><strong>7-15<\/strong><\/td>\n<td><strong>5.five-41<\/strong><\/td>\n<td><strong>1000-2600<\/strong><\/td>\n<td><strong>50<\/strong><\/td>\n<td><strong>2.five-five<\/strong><\/td>\n<td><strong>178<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>50HS-C<\/strong><\/td>\n<td><strong>thirty<\/strong><\/td>\n<td><strong>39.six-86.four<\/strong><\/td>\n<td><strong>11-24<\/strong><\/td>\n<td><strong>twelve-64<\/strong><\/td>\n<td><strong>1300-2700<\/strong><\/td>\n<td><strong>fifty five<\/strong><\/td>\n<td><strong>four-six<\/strong><\/td>\n<td><strong>214<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>50HSR-C<\/strong><\/td>\n<td><strong>30<\/strong><\/td>\n<td><strong>36-seventy five.6<\/strong><\/td>\n<td><strong>ten-21<\/strong><\/td>\n<td><strong>13-39<\/strong><\/td>\n<td><strong>1300-2100<\/strong><\/td>\n<td><strong> <\/strong><\/td>\n<td><strong>2-4<\/strong><\/td>\n<td><strong>213<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>50HHS-D<\/strong><\/td>\n<td><strong>sixty<\/strong><\/td>\n<td><strong>68.4-136.eight<\/strong><\/td>\n<td><strong>19-38<\/strong><\/td>\n<td><strong>twenty five-87<\/strong><\/td>\n<td><strong>850-1400<\/strong><\/td>\n<td><strong>forty seven<\/strong><\/td>\n<td><strong>3-seven.5<\/strong><\/td>\n<td><strong>457<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>75HS-C<\/strong><\/td>\n<td><strong>30<\/strong><\/td>\n<td><strong>86.4-198<\/strong><\/td>\n<td><strong>24-fifty five<\/strong><\/td>\n<td><strong>nine-fifty two<\/strong><\/td>\n<td><strong>a thousand-2200<\/strong><\/td>\n<td><strong>71<\/strong><\/td>\n<td><strong>4-6<\/strong><\/td>\n<td><strong>245<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>75HS-D<\/strong><\/td>\n<td><strong>sixty<\/strong><\/td>\n<td><strong>86.4-198<\/strong><\/td>\n<td><strong>24-fifty five<\/strong><\/td>\n<td><strong>nine-52<\/strong><\/td>\n<td><strong>one thousand-2200<\/strong><\/td>\n<td><strong>seventy one<\/strong><\/td>\n<td><strong>four-six<\/strong><\/td>\n<td><strong>245<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>75HSR-C<\/strong><\/td>\n<td><strong>thirty<\/strong><\/td>\n<td><strong>seventy nine.2-180<\/strong><\/td>\n<td><strong>22-50<\/strong><\/td>\n<td><strong>5-34.5<\/strong><\/td>\n<td><strong>800-1800<\/strong><\/td>\n<td><strong>59<\/strong><\/td>\n<td><strong>three-five<\/strong><\/td>\n<td><strong>245<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>75HSR-D<\/strong><\/td>\n<td><strong>sixty<\/strong><\/td>\n<td><strong>seventy nine.2-a hundred and eighty<\/strong><\/td>\n<td><strong>22-50<\/strong><\/td>\n<td><strong>five-34.5<\/strong><\/td>\n<td><strong>800-1800<\/strong><\/td>\n<td><strong>fifty nine<\/strong><\/td>\n<td><strong>3-5<\/strong><\/td>\n<td><strong>245<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>100HS-D<\/strong><\/td>\n<td><strong>60<\/strong><\/td>\n<td><strong>162-360<\/strong><\/td>\n<td><strong>forty five-a hundred<\/strong><\/td>\n<td><strong>12-56<\/strong><\/td>\n<td><strong>800-1550<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>5-8<\/strong><\/td>\n<td><strong>365<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>100HS-E<\/strong><\/td>\n<td><strong>one hundred twenty<\/strong><\/td>\n<td><strong>162-360<\/strong><\/td>\n<td><strong>45-a hundred<\/strong><\/td>\n<td><strong>12-fifty six<\/strong><\/td>\n<td><strong>800-1550<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>5-eight<\/strong><\/td>\n<td><strong>365<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>100HSR-D<\/strong><\/td>\n<td><strong>60<\/strong><\/td>\n<td><strong>one hundred forty four-324<\/strong><\/td>\n<td><strong>forty-ninety<\/strong><\/td>\n<td><strong>twelve-45<\/strong><\/td>\n<td><strong>800-1350<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>3-five<\/strong><\/td>\n<td><strong>365<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>100HSR-E<\/strong><\/td>\n<td><strong>a hundred and twenty<\/strong><\/td>\n<td><strong>one hundred forty four-324<\/strong><\/td>\n<td><strong>forty-90<\/strong><\/td>\n<td><strong>twelve-45<\/strong><\/td>\n<td><strong>800-1350<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>3-5<\/strong><\/td>\n<td><strong>365<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>100HHS-F<\/strong><\/td>\n<td><strong>260<\/strong><\/td>\n<td><strong>324-720<\/strong><\/td>\n<td><strong>ninety-two hundred<\/strong><\/td>\n<td><strong>thirty-118<\/strong><\/td>\n<td><strong>600-1000<\/strong><\/td>\n<td><strong>sixty four<\/strong><\/td>\n<td><strong>three-eight<\/strong><\/td>\n<td><strong>711<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>150HS-E<\/strong><\/td>\n<td><strong>one hundred twenty<\/strong><\/td>\n<td><strong>360-828<\/strong><\/td>\n<td><strong>100-230<\/strong><\/td>\n<td><strong>ten-61<\/strong><\/td>\n<td><strong>five hundred-1140<\/strong><\/td>\n<td><strong>seventy two<\/strong><\/td>\n<td><strong>2-9<\/strong><\/td>\n<td><strong>510<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>150HS-S<\/strong><\/td>\n<td><strong>three hundred<\/strong><\/td>\n<td><strong>360-828<\/strong><\/td>\n<td><strong>one hundred-230<\/strong><\/td>\n<td><strong>10-sixty one<\/strong><\/td>\n<td><strong>five hundred-1140<\/strong><\/td>\n<td><strong>seventy two<\/strong><\/td>\n<td><strong>two-nine<\/strong><\/td>\n<td><strong>510<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>150HSR-E<\/strong><\/td>\n<td><strong>a hundred and twenty<\/strong><\/td>\n<td><strong>324-720<\/strong><\/td>\n<td><strong>90-two hundred<\/strong><\/td>\n<td><strong>7-forty nine<\/strong><\/td>\n<td><strong>four hundred-a thousand<\/strong><\/td>\n<td><strong>sixty five<\/strong><\/td>\n<td><strong>five-10<\/strong><\/td>\n<td><strong>510<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>150HSR-R<\/strong><\/td>\n<td><strong>300<\/strong><\/td>\n<td><strong>324-720<\/strong><\/td>\n<td><strong>ninety-two hundred<\/strong><\/td>\n<td><strong>7-49<\/strong><\/td>\n<td><strong>400-1000<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>five-10<\/strong><\/td>\n<td><strong>510<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>150HHS-S<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>468-1008<\/strong><\/td>\n<td><strong>a hundred thirty-280<\/strong><\/td>\n<td><strong>twenty-94<\/strong><\/td>\n<td><strong>five hundred-a thousand<\/strong><\/td>\n<td><strong>65<\/strong><\/td>\n<td><strong>4-12<\/strong><\/td>\n<td><strong>711<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>200HS-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>612-1368<\/strong><\/td>\n<td><strong>a hundred and seventy-380<\/strong><\/td>\n<td><strong>eleven-61<\/strong><\/td>\n<td><strong>four hundred-850<\/strong><\/td>\n<td><strong>seventy one<\/strong><\/td>\n<td><strong>4-10<\/strong><\/td>\n<td><strong>686<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>200HSR-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>540-1188<\/strong><\/td>\n<td><strong>two hundred-450<\/strong><\/td>\n<td><strong>seven-forty five<\/strong><\/td>\n<td><strong>300-650<\/strong><\/td>\n<td><strong>eighty<\/strong><\/td>\n<td><strong>2.five-7.five<\/strong><\/td>\n<td><strong>686<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>200MS-E<\/strong><\/td>\n<td><strong>120<\/strong><\/td>\n<td><strong>540-1440<\/strong><\/td>\n<td><strong>a hundred and fifty-400<\/strong><\/td>\n<td><strong>14-sixty<\/strong><\/td>\n<td><strong>600-one thousand<\/strong><\/td>\n<td><strong>73<\/strong><\/td>\n<td><strong>4-ten<\/strong><\/td>\n<td><strong>549<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>200MS-R<\/strong><\/td>\n<td><strong>300<\/strong><\/td>\n<td><strong>540-1440<\/strong><\/td>\n<td><strong>a hundred and fifty-400<\/strong><\/td>\n<td><strong>fourteen-60<\/strong><\/td>\n<td><strong>600-1000<\/strong><\/td>\n<td><strong>seventy three<\/strong><\/td>\n<td><strong>four-10<\/strong><\/td>\n<td><strong>549<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>250HS-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>936-1980<\/strong><\/td>\n<td><strong>260-550<\/strong><\/td>\n<td><strong>7-68<\/strong><\/td>\n<td><strong>300-800<\/strong><\/td>\n<td><strong>82<\/strong><\/td>\n<td><strong>six<\/strong><\/td>\n<td><strong>762<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>250HSR-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>720-1620<\/strong><\/td>\n<td><strong>320-seven-hundred<\/strong><\/td>\n<td><strong>13-14<\/strong><\/td>\n<td><strong>300-500<\/strong><\/td>\n<td><strong>seventy nine<\/strong><\/td>\n<td><strong>3-eight<\/strong><\/td>\n<td><strong>762<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>300HS-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>1260-2772<\/strong><\/td>\n<td><strong>350-770<\/strong><\/td>\n<td><strong>thirteen-63<\/strong><\/td>\n<td><strong>three hundred-600<\/strong><\/td>\n<td><strong>77<\/strong><\/td>\n<td><strong>three-ten<\/strong><\/td>\n<td><strong>965<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>300HSR-ST<\/strong><\/td>\n<td><strong>560<\/strong><\/td>\n<td><strong>1152-2520<\/strong><\/td>\n<td><strong>380-850<\/strong><\/td>\n<td><strong>11-sixty three<\/strong><\/td>\n<td><strong>250-550<\/strong><\/td>\n<td><strong>seventy nine<\/strong><\/td>\n<td><strong>4-10<\/strong><\/td>\n<td><strong>965<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>350HS-ST<\/strong><\/td>\n<td><strong>1200<\/strong><\/td>\n<td><strong>1368-3060<\/strong><\/td>\n<td><strong>380-850<\/strong><\/td>\n<td><strong>eleven-63<\/strong><\/td>\n<td><strong>250-550<\/strong><\/td>\n<td><strong>seventy nine<\/strong><\/td>\n<td><strong>four-10<\/strong><\/td>\n<td><strong>1067<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>400HS-TU<\/strong><\/td>\n<td><strong>1200<\/strong><\/td>\n<td><strong>2160-5054<\/strong><\/td>\n<td><strong>600-1400<\/strong><\/td>\n<td><strong>8-sixty six<\/strong><\/td>\n<td><strong>200-five hundred<\/strong><\/td>\n<td><strong>eighty<\/strong><\/td>\n<td><strong>4.5-9<\/strong><\/td>\n<td><strong>1245<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>450HS-TU<\/strong><\/td>\n<td><strong>1200<\/strong><\/td>\n<td><strong>2520-5400<\/strong><\/td>\n<td><strong>700-1500<\/strong><\/td>\n<td><strong>13-57<\/strong><\/td>\n<td><strong>two hundred-400<\/strong><\/td>\n<td><strong>85<\/strong><\/td>\n<td><strong>5-ten<\/strong><\/td>\n<td><strong>1370<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Remark:<\/strong><br \/><strong>one.Capability range advised:50%Q&#8217; leQ le110%Q'(Q&#8217; Appropriate to potential at highest efficiency level).<br \/>two.NPSH: suitable to stage Q advised at greatest velocity.<\/strong><\/p>\n<p><strong>Construction of EPT EPT:<\/p>\n<p><\/strong><\/p>\n<p><strong>Application:<\/strong><br \/><strong>HS(R) sequence slurry pump is widely employed in metallurgy, mining, EPTral processing, dredging, de-watering, drinking water remedy, coal washing, mill, cyclone feed, EPTTng, EPTT, creating substance&#8230;and so on. numerous EPTT sites. HS pumps are called different names for diverse functioning obligations: Mineral processing pump, Mill discharge slurry EPT, EPTTter pump, Feeding pump, EPTEPTTng pump,Transfer pump Thickner Underflow EPT, De-watering EPT pump, Force pump, Focus pump&#8230;<\/strong><\/p>\n<p><strong> <\/strong>                            <\/p>\n<p>\n<p><img decoding=\"async\" style=\"height:autowidth: auto\" title=\"  in Bhiwandi India  sales   price   shop   near me   near me shop   factory   supplier Heavy Duty Mining Processing Centrifugal Slurry Pump Ce ISO SGS Approved manufacturer   best   Cost   Custom   Cheap   wholesaler \" src=\"http:\/\/img.hzpt.com\/uploads\/images\/Jcj\/coupling2.jpg\" alt=\"  in Bhiwandi India  sales   price   shop   near me   near me shop   factory   supplier Heavy Duty Mining Processing Centrifugal Slurry Pump Ce ISO SGS Approved manufacturer   best   Cost   Custom   Cheap   wholesaler \" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>In this way, our merchandise have continued to acquire industry acceptance and clients gratification above the previous couple of several years. Furthermore, WE CAN Make Tailored VARIATORS, GEARED MOTORS, Electric powered MOTORS AND OTHER HYDRAULIC Merchandise According TO CUSTOMERS\u2019 DRAWINGS. With a lot of years&#8217; expertise in this line, we will be trustworthy by our [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1743","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/posts\/1743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/comments?post=1743"}],"version-history":[{"count":1,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/posts\/1743\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/posts\/1743\/revisions\/2169"}],"wp:attachment":[{"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/media?parent=1743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/categories?post=1743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flangecoupling.top\/hi\/wp-json\/wp\/v2\/tags?post=1743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}